{"id":2552,"date":"2022-04-09T22:04:53","date_gmt":"2022-04-09T22:04:53","guid":{"rendered":"https:\/\/www.hojaldresdivali.com.co\/?post_type=portfolio&#038;p=2552"},"modified":"2024-12-04T17:38:09","modified_gmt":"2024-12-04T22:38:09","slug":"arbol-con-estrellas-de-navidad","status":"publish","type":"portfolio","link":"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/arbol-con-estrellas-de-navidad\/","title":{"rendered":"\u00c1rbol con Estrellas de Navidad"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>Una linda y f\u00e1cil receta con hojaldre para sorprender en Navidad.<\/p>\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-medium-font-size\">Ingredientes<\/h2>\n\n\n\n<ul id=\"block-ff7cbefe-c0de-44e3-9b25-665330699e2b\" class=\"wp-block-list\">\n<li>500g. Masa de Hojaldre DIVALI pre-estirada<\/li>\n\n\n\n<li>200g. de Chocolate de untar<\/li>\n\n\n\n<li>100g. de Az\u00facar pulverizada<\/li>\n\n\n\n<li>Grageas navide\u00f1as<\/li>\n\n\n\n<li>Huevo<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-medium-font-size\">Informaci\u00f3n<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Porciones:<\/strong>\u00a015 a 18<\/li>\n\n\n\n<li><strong>Tiempo de preparaci\u00f3n:<\/strong>\u00a010 Minutos<\/li>\n\n\n\n<li><strong>Tiempo de horneo:<\/strong> 20 Minutos<\/li>\n\n\n\n<li><strong>Complejidad:<\/strong>\u00a0Baja<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-medium-font-size\">Utensilios<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Moldes de Estrellas de varios tama\u00f1os<\/li>\n\n\n\n<li>Rodillo<\/li>\n\n\n\n<li>Brocha<\/li>\n\n\n\n<li>Esp\u00e1tula<\/li>\n\n\n\n<li>Bandeja para horno<\/li>\n\n\n\n<li>Horno Convencional (NO microondas)<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-medium-font-size\">Nota del chef<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Puedes reemplazar el chocolate de untar por mermelada o alguna crema de sal.<\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">Preparaci\u00f3n<\/h2>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Saca el hojaldre del congelador. Si lo dejaste en refrigeraci\u00f3n el d\u00eda anterior, no lo saques hasta cuando sea el momento de usarlo.\u00a0<\/li>\n\n\n\n<li>Pre-calentar el horno a 180\u00baC o 350\u00baF.<\/li>\n\n\n\n<li>Engrasa la lata de horneo con un poco de aceite.<\/li>\n\n\n\n<li>En una superficie uniforme y fr\u00eda espolvorea harina de trigo y coloca la masa de hojaldre DIVALI.\u00a0<\/li>\n\n\n\n<li>Estira la masa de hojaldre DIVALI y con ayuda del rodillo adelgaza la masa hasta lograr un grosor de 2 mil\u00edmetros.\u00a0<\/li>\n\n\n\n<li>Con los moldes de estrellas corta las estrellas de diferente tama\u00f1o.<\/li>\n\n\n\n<li>Acomoda cada estrellita en la bandeja para horno dejando 1.5cm de espacio entre ellas.<\/li>\n\n\n\n<li>Bate el huevo completo y pinta la superficie de cada estrella.<\/li>\n\n\n\n<li>Hornea durante 20 minutos o hasta dorar.<\/li>\n\n\n\n<li>Saca del horno y deja enfriar.<\/li>\n\n\n\n<li>Arma el \u00e1rbol teniendo como base la estrella mas grande, agr\u00e9gale una capa e chocolate para untar y coloca la estrella que le sigue en tama\u00f1o y agrega de nuevo una capa de chocolate. Sigue el mismo procedimiento con las otras estrellas de mayor a menor tama\u00f1o intercalando las puntas.\u00a0<\/li>\n\n\n\n<li>Adorna a tu gusto con grageas navide\u00f1as y az\u00facar pulverizada.<\/li>\n\n\n\n<li>\u00a1Sirve y disfruta!<\/li>\n<\/ol>\n\n\n\n<div style=\"height:55px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"porto-block\" data-id=\"2745\">[vc_row][vc_column width=\"1\/2\"][vc_column_text]<img decoding=\"async\" src=\"https:\/\/www.hojaldresdivali.com.co\/wp-content\/uploads\/2022\/05\/CompraAqui.png\" alt=\"\" width=\"201\" height=\"189\" \/>\r\n<h2>\u00a1Compra aqu\u00ed!<\/h2>\r\n\u00a1Tus productos favoritos para disfrutarlos donde quieras\u00a1\r\n\r\n<a role=\"button\" href=\"https:\/\/www.hojaldresdivali.com.co\/masa-de-hojaldre\/\">\r\nCompra aqu\u00ed\r\n<\/a>\r\n[\/vc_column_text][\/vc_column][vc_column width=\"1\/2\"][vc_column_text]<img decoding=\"async\" src=\"https:\/\/www.hojaldresdivali.com.co\/wp-content\/uploads\/2022\/05\/NuestrosTips.png\" alt=\"\" width=\"192\" height=\"198\" \/>\r\n<h2>Tips<\/h2>\r\nTe compartimos nuestros mejores secretos para que seas un experto. \u00a1Y te enamores del hojaldre!\r\n\r\n<a role=\"button\" href=\"https:\/\/www.hojaldresdivali.com.co\/divali-tips\">\r\nNuestros tips\r\n<\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Una linda y f\u00e1cil receta con hojaldre para sorprender en Navidad. Ingredientes Informaci\u00f3n Utensilios Nota del chef Puedes reemplazar el chocolate de untar por mermelada o alguna crema de sal. Preparaci\u00f3n<\/p>\n","protected":false},"featured_media":2555,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"portfolio_cat":[101,100,98],"portfolio_skills":[],"class_list":["post-2552","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_cat-dulce","portfolio_cat-postre","portfolio_cat-snack"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c1rbol con Estrellas de Navidad - Hojaldres Divali<\/title>\n<meta name=\"description\" content=\"\u00c1rbol con Estrellas de Navidad. Una linda y f\u00e1cil receta con hojaldre para sorprender en Navidad. Revisa y aprende esta receta aqu\u00ed.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras%20recetas\/arbol-con-estrellas-de-navidad\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c1rbol con Estrellas de Navidad - Hojaldres Divali\" \/>\n<meta property=\"og:description\" content=\"\u00c1rbol con Estrellas de Navidad. Una linda y f\u00e1cil receta con hojaldre para sorprender en Navidad. Revisa y aprende esta receta aqu\u00ed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/arbol-con-estrellas-de-navidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Hojaldres Divali\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HojaldresYDeliciasDivali\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-04T22:38:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hojaldresdivali.com.co\/wp-content\/uploads\/2022\/04\/ArbolEstrellas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"658\" \/>\n\t<meta property=\"og:image:height\" content=\"659\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/en\\\/Nuestras recetas\\\/arbol-con-estrellas-de-navidad\\\/\",\"url\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/en\\\/Nuestras recetas\\\/arbol-con-estrellas-de-navidad\\\/\",\"name\":\"\u00c1rbol con Estrellas de Navidad - Hojaldres Divali\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/en\\\/Nuestras recetas\\\/arbol-con-estrellas-de-navidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/en\\\/Nuestras recetas\\\/arbol-con-estrellas-de-navidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/ArbolEstrellas.jpg\",\"datePublished\":\"2022-04-09T22:04:53+00:00\",\"dateModified\":\"2024-12-04T22:38:09+00:00\",\"description\":\"\u00c1rbol con Estrellas de Navidad. Una linda y f\u00e1cil receta con hojaldre para sorprender en Navidad. Revisa y aprende esta receta aqu\u00ed.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/en\\\/Nuestras recetas\\\/arbol-con-estrellas-de-navidad\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/en\\\/Nuestras recetas\\\/arbol-con-estrellas-de-navidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/en\\\/Nuestras recetas\\\/arbol-con-estrellas-de-navidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/ArbolEstrellas.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/ArbolEstrellas.jpg\",\"width\":658,\"height\":659},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/en\\\/Nuestras recetas\\\/arbol-con-estrellas-de-navidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestras recetas\",\"item\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/en\\\/Nuestras recetas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c1rbol con Estrellas de Navidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\\\/#website\",\"url\":\"https:\\\/\\\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\\\/\",\"name\":\"Hojaldres Divali\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\\\/\\\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\\\/#organization\",\"name\":\"Hojaldres Divali\",\"url\":\"https:\\\/\\\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/LogoNew.png\",\"contentUrl\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/LogoNew.png\",\"width\":805,\"height\":649,\"caption\":\"Hojaldres Divali\"},\"image\":{\"@id\":\"https:\\\/\\\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/HojaldresYDeliciasDivali\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCcyMJJCW32fNptgHuC81mSw\\\/videos\",\"https:\\\/\\\/www.instagram.com\\\/hojaldresdivali\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c1rbol con Estrellas de Navidad - Hojaldres Divali","description":"\u00c1rbol con Estrellas de Navidad. Una linda y f\u00e1cil receta con hojaldre para sorprender en Navidad. Revisa y aprende esta receta aqu\u00ed.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/arbol-con-estrellas-de-navidad\/","og_locale":"en_US","og_type":"article","og_title":"\u00c1rbol con Estrellas de Navidad - Hojaldres Divali","og_description":"\u00c1rbol con Estrellas de Navidad. Una linda y f\u00e1cil receta con hojaldre para sorprender en Navidad. Revisa y aprende esta receta aqu\u00ed.","og_url":"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/arbol-con-estrellas-de-navidad\/","og_site_name":"Hojaldres Divali","article_publisher":"https:\/\/www.facebook.com\/HojaldresYDeliciasDivali","article_modified_time":"2024-12-04T22:38:09+00:00","og_image":[{"width":658,"height":659,"url":"https:\/\/www.hojaldresdivali.com.co\/wp-content\/uploads\/2022\/04\/ArbolEstrellas.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/arbol-con-estrellas-de-navidad\/","url":"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/arbol-con-estrellas-de-navidad\/","name":"\u00c1rbol con Estrellas de Navidad - Hojaldres Divali","isPartOf":{"@id":"https:\/\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/arbol-con-estrellas-de-navidad\/#primaryimage"},"image":{"@id":"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/arbol-con-estrellas-de-navidad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hojaldresdivali.com.co\/wp-content\/uploads\/2022\/04\/ArbolEstrellas.jpg","datePublished":"2022-04-09T22:04:53+00:00","dateModified":"2024-12-04T22:38:09+00:00","description":"\u00c1rbol con Estrellas de Navidad. Una linda y f\u00e1cil receta con hojaldre para sorprender en Navidad. Revisa y aprende esta receta aqu\u00ed.","breadcrumb":{"@id":"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/arbol-con-estrellas-de-navidad\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/arbol-con-estrellas-de-navidad\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/arbol-con-estrellas-de-navidad\/#primaryimage","url":"https:\/\/www.hojaldresdivali.com.co\/wp-content\/uploads\/2022\/04\/ArbolEstrellas.jpg","contentUrl":"https:\/\/www.hojaldresdivali.com.co\/wp-content\/uploads\/2022\/04\/ArbolEstrellas.jpg","width":658,"height":659},{"@type":"BreadcrumbList","@id":"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/arbol-con-estrellas-de-navidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hojaldresdivali.com.co\/en\/"},{"@type":"ListItem","position":2,"name":"Nuestras recetas","item":"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/"},{"@type":"ListItem","position":3,"name":"\u00c1rbol con Estrellas de Navidad"}]},{"@type":"WebSite","@id":"https:\/\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\/#website","url":"https:\/\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\/","name":"Hojaldres Divali","description":"Just another WordPress site","publisher":{"@id":"https:\/\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\/#organization","name":"Hojaldres Divali","url":"https:\/\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.hojaldresdivali.com.co\/wp-content\/uploads\/2022\/05\/LogoNew.png","contentUrl":"https:\/\/www.hojaldresdivali.com.co\/wp-content\/uploads\/2022\/05\/LogoNew.png","width":805,"height":649,"caption":"Hojaldres Divali"},"image":{"@id":"https:\/\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HojaldresYDeliciasDivali","https:\/\/www.youtube.com\/channel\/UCcyMJJCW32fNptgHuC81mSw\/videos","https:\/\/www.instagram.com\/hojaldresdivali\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.hojaldresdivali.com.co\/en\/wp-json\/wp\/v2\/portfolio\/2552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hojaldresdivali.com.co\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.hojaldresdivali.com.co\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hojaldresdivali.com.co\/en\/wp-json\/wp\/v2\/comments?post=2552"}],"version-history":[{"count":0,"href":"https:\/\/www.hojaldresdivali.com.co\/en\/wp-json\/wp\/v2\/portfolio\/2552\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hojaldresdivali.com.co\/en\/wp-json\/wp\/v2\/media\/2555"}],"wp:attachment":[{"href":"https:\/\/www.hojaldresdivali.com.co\/en\/wp-json\/wp\/v2\/media?parent=2552"}],"wp:term":[{"taxonomy":"portfolio_cat","embeddable":true,"href":"https:\/\/www.hojaldresdivali.com.co\/en\/wp-json\/wp\/v2\/portfolio_cat?post=2552"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/www.hojaldresdivali.com.co\/en\/wp-json\/wp\/v2\/portfolio_skills?post=2552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}