{"id":2572,"date":"2022-04-09T23:48:38","date_gmt":"2022-04-09T23:48:38","guid":{"rendered":"https:\/\/www.hojaldresdivali.com.co\/?post_type=portfolio&#038;p=2572"},"modified":"2024-12-02T17:39:55","modified_gmt":"2024-12-02T22:39:55","slug":"galletas-con-mermelada","status":"publish","type":"portfolio","link":"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/galletas-con-mermelada\/","title":{"rendered":"Galletas con Mermelada"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>Prepara estas lindas galletas de navidad y comparte con los que m\u00e1s quieres.<\/p>\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"has-medium-font-size wp-block-heading\">Ingredientes<\/h2>\n\n\n\n<ul class=\"wp-block-list\" id=\"block-ff7cbefe-c0de-44e3-9b25-665330699e2b\"><li>500g. Masa de Hojaldre DIVALI pre-estirada<\/li><li>200g. de Mermeladas de cualquier sabor<\/li><li>Huevo<\/li><li>100g. de Az\u00facar Pulverizadavo<\/li><\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"has-medium-font-size wp-block-heading\">Informaci\u00f3n<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Porciones:<\/strong>\u00a010 a 12<\/li><li><strong>Tiempo de preparaci\u00f3n:<\/strong>\u00a010 Minutos<\/li><li><strong>Tiempo de Horneo:<\/strong> 20 Minutos<\/li><li><strong>Complejidad:<\/strong>\u00a0Baja<\/li><\/ul>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"has-medium-font-size wp-block-heading\">Utensilios<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Cortadores de Navidad de diferentes formas<\/li><li>Cortadores redondos o de otras formas<\/li><li>Rodillo<\/li><li>Brocha<\/li><li>Esp\u00e1tula<\/li><li>Bandeja para horno<\/li><li>Horno Convencional (NO microondas)<\/li><\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"has-medium-font-size wp-block-heading\">Nota del chef<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Puedes adornar el plato con l\u00edneas de cubierta de chocolate y un poco de polvo dorado para resaltar las galletas.<\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Preparaci\u00f3n<\/h2>\n\n\n\n<ol class=\"wp-block-list\"><li>Saca el hojaldre del congelador. Si lo dejaste en refrigeraci\u00f3n el d\u00eda anterior, no lo saques hasta cuando sea el momento de usarlo.\u00a0<\/li><li>Pre-calentar el horno a 180\u00baC o 350\u00baF.<\/li><li>Engrasa la lata de horneo con un poco de aceite.<\/li><li>En una superficie uniforme y fr\u00eda espolvorea harina de trigo y coloca la masa de hojaldre DIVALI.\u00a0<\/li><li>Estira la masa de hojaldre DIVALI y con ayuda del rodillo adelgaza la masa hasta lograr un grosor de 2 mil\u00edmetros.\u00a0<\/li><li>Cortar con el molde redondo dos c\u00edrculos de hojaldre.<\/li><li>En uno de los c\u00edrculos corta una figura navide\u00f1a en el centro de ella y res\u00e9rvala. Nota: puedes hacer formas diferentes a los c\u00edrculos.<\/li><li>Acomoda\u00a0 los dos c\u00edrculos y la figura navide\u00f1a cortada de uno de los c\u00edrculos\u00a0 en la bandeja para horno dejando 1.5cm de espacio entre ellas.<\/li><li>Con un tenedor pincha los c\u00edrculos y cuadrados completos que ser\u00e1n la base.<\/li><li>Bate el huevo completo y pinta la superficie de todas las figuras.<\/li><li>Hornea durante 20 minutos o hasta dorar.<\/li><li>Saca del horno y deja enfriar.<\/li><li>Coloca la mermelada sobre la figura de base y res\u00e9rvala.<\/li><li>Coloca sobre un plato aparte los c\u00edrculos o cuadrados con la figura navide\u00f1a en el centro y con un colador espolvorea az\u00facar pulverizada sobre la superficie.<\/li><li>Coloca el c\u00edrculo o cuadrado con figura sobre los otros con la mermelada y en el centro ubica la figurita navide\u00f1a correspondiente.<\/li><li>Coloca en una bandeja con decoraci\u00f3n a tu gusto.<\/li><li>\u00a1Sirve y disfruta!<\/li><\/ol>\n\n\n\n<div style=\"height:55px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"porto-block\" data-id=\"2745\">[vc_row][vc_column width=\"1\/2\"][vc_column_text]<img decoding=\"async\" src=\"https:\/\/www.hojaldresdivali.com.co\/wp-content\/uploads\/2022\/05\/CompraAqui.png\" alt=\"\" width=\"201\" height=\"189\" \/>\r\n<h2>\u00a1Compra aqu\u00ed!<\/h2>\r\n\u00a1Tus productos favoritos para disfrutarlos donde quieras\u00a1\r\n\r\n<a role=\"button\" href=\"https:\/\/www.hojaldresdivali.com.co\/masa-de-hojaldre\/\">\r\nCompra aqu\u00ed\r\n<\/a>\r\n[\/vc_column_text][\/vc_column][vc_column width=\"1\/2\"][vc_column_text]<img decoding=\"async\" src=\"https:\/\/www.hojaldresdivali.com.co\/wp-content\/uploads\/2022\/05\/NuestrosTips.png\" alt=\"\" width=\"192\" height=\"198\" \/>\r\n<h2>Tips<\/h2>\r\nTe compartimos nuestros mejores secretos para que seas un experto. \u00a1Y te enamores del hojaldre!\r\n\r\n<a role=\"button\" href=\"https:\/\/www.hojaldresdivali.com.co\/divali-tips\">\r\nNuestros tips\r\n<\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Prepara estas lindas galletas de navidad y comparte con los que m\u00e1s quieres. Ingredientes 500g. Masa de Hojaldre DIVALI pre-estirada 200g. de Mermeladas de cualquier sabor Huevo 100g. de Az\u00facar Pulverizadavo Informaci\u00f3n Porciones:\u00a010 a 12 Tiempo de preparaci\u00f3n:\u00a010 Minutos Tiempo de Horneo: 20 Minutos Complejidad:\u00a0Baja Utensilios Cortadores de Navidad de diferentes formas Cortadores redondos o [&hellip;]<\/p>\n","protected":false},"featured_media":2573,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"portfolio_cat":[101,97,100,98],"portfolio_skills":[],"class_list":["post-2572","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_cat-dulce","portfolio_cat-pasaboca","portfolio_cat-postre","portfolio_cat-snack"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Galletas con Mermelada - Hojaldres Divali<\/title>\n<meta name=\"description\" content=\"Galletas con Mermelada. Prepara estas lindas galletas de Navidad y comparte con los que m\u00e1s quieres. \u00a1Aprende esta receta aqu\u00ed!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras%20recetas\/galletas-con-mermelada\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Galletas con Mermelada - Hojaldres Divali\" \/>\n<meta property=\"og:description\" content=\"Galletas con Mermelada. Prepara estas lindas galletas de Navidad y comparte con los que m\u00e1s quieres. \u00a1Aprende esta receta aqu\u00ed!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/galletas-con-mermelada\/\" \/>\n<meta property=\"og:site_name\" content=\"Hojaldres Divali\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HojaldresYDeliciasDivali\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-02T22:39:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hojaldresdivali.com.co\/wp-content\/uploads\/2022\/04\/GalletasMermelada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"658\" \/>\n\t<meta property=\"og:image:height\" content=\"659\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/en\\\/Nuestras recetas\\\/galletas-con-mermelada\\\/\",\"url\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/en\\\/Nuestras recetas\\\/galletas-con-mermelada\\\/\",\"name\":\"Galletas con Mermelada - Hojaldres Divali\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/en\\\/Nuestras recetas\\\/galletas-con-mermelada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/en\\\/Nuestras recetas\\\/galletas-con-mermelada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/GalletasMermelada.jpg\",\"datePublished\":\"2022-04-09T23:48:38+00:00\",\"dateModified\":\"2024-12-02T22:39:55+00:00\",\"description\":\"Galletas con Mermelada. Prepara estas lindas galletas de Navidad y comparte con los que m\u00e1s quieres. \u00a1Aprende esta receta aqu\u00ed!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/en\\\/Nuestras recetas\\\/galletas-con-mermelada\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/en\\\/Nuestras recetas\\\/galletas-con-mermelada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/en\\\/Nuestras recetas\\\/galletas-con-mermelada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/GalletasMermelada.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/GalletasMermelada.jpg\",\"width\":658,\"height\":659},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/en\\\/Nuestras recetas\\\/galletas-con-mermelada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestras recetas\",\"item\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/en\\\/Nuestras recetas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Galletas con Mermelada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\\\/#website\",\"url\":\"https:\\\/\\\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\\\/\",\"name\":\"Hojaldres Divali\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\\\/\\\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\\\/#organization\",\"name\":\"Hojaldres Divali\",\"url\":\"https:\\\/\\\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/LogoNew.png\",\"contentUrl\":\"https:\\\/\\\/www.hojaldresdivali.com.co\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/LogoNew.png\",\"width\":805,\"height\":649,\"caption\":\"Hojaldres Divali\"},\"image\":{\"@id\":\"https:\\\/\\\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/HojaldresYDeliciasDivali\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCcyMJJCW32fNptgHuC81mSw\\\/videos\",\"https:\\\/\\\/www.instagram.com\\\/hojaldresdivali\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Galletas con Mermelada - Hojaldres Divali","description":"Galletas con Mermelada. Prepara estas lindas galletas de Navidad y comparte con los que m\u00e1s quieres. \u00a1Aprende esta receta aqu\u00ed!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/galletas-con-mermelada\/","og_locale":"en_US","og_type":"article","og_title":"Galletas con Mermelada - Hojaldres Divali","og_description":"Galletas con Mermelada. Prepara estas lindas galletas de Navidad y comparte con los que m\u00e1s quieres. \u00a1Aprende esta receta aqu\u00ed!","og_url":"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/galletas-con-mermelada\/","og_site_name":"Hojaldres Divali","article_publisher":"https:\/\/www.facebook.com\/HojaldresYDeliciasDivali","article_modified_time":"2024-12-02T22:39:55+00:00","og_image":[{"width":658,"height":659,"url":"https:\/\/www.hojaldresdivali.com.co\/wp-content\/uploads\/2022\/04\/GalletasMermelada.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/galletas-con-mermelada\/","url":"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/galletas-con-mermelada\/","name":"Galletas con Mermelada - Hojaldres Divali","isPartOf":{"@id":"https:\/\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/galletas-con-mermelada\/#primaryimage"},"image":{"@id":"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/galletas-con-mermelada\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hojaldresdivali.com.co\/wp-content\/uploads\/2022\/04\/GalletasMermelada.jpg","datePublished":"2022-04-09T23:48:38+00:00","dateModified":"2024-12-02T22:39:55+00:00","description":"Galletas con Mermelada. Prepara estas lindas galletas de Navidad y comparte con los que m\u00e1s quieres. \u00a1Aprende esta receta aqu\u00ed!","breadcrumb":{"@id":"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/galletas-con-mermelada\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/galletas-con-mermelada\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/galletas-con-mermelada\/#primaryimage","url":"https:\/\/www.hojaldresdivali.com.co\/wp-content\/uploads\/2022\/04\/GalletasMermelada.jpg","contentUrl":"https:\/\/www.hojaldresdivali.com.co\/wp-content\/uploads\/2022\/04\/GalletasMermelada.jpg","width":658,"height":659},{"@type":"BreadcrumbList","@id":"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/galletas-con-mermelada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hojaldresdivali.com.co\/en\/"},{"@type":"ListItem","position":2,"name":"Nuestras recetas","item":"https:\/\/www.hojaldresdivali.com.co\/en\/Nuestras recetas\/"},{"@type":"ListItem","position":3,"name":"Galletas con Mermelada"}]},{"@type":"WebSite","@id":"https:\/\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\/#website","url":"https:\/\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\/","name":"Hojaldres Divali","description":"Just another WordPress site","publisher":{"@id":"https:\/\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\/#organization","name":"Hojaldres Divali","url":"https:\/\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.hojaldresdivali.com.co\/wp-content\/uploads\/2022\/05\/LogoNew.png","contentUrl":"https:\/\/www.hojaldresdivali.com.co\/wp-content\/uploads\/2022\/05\/LogoNew.png","width":805,"height":649,"caption":"Hojaldres Divali"},"image":{"@id":"https:\/\/hojaldres-divali-a693bd.ingress-comporellon.easywp.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HojaldresYDeliciasDivali","https:\/\/www.youtube.com\/channel\/UCcyMJJCW32fNptgHuC81mSw\/videos","https:\/\/www.instagram.com\/hojaldresdivali\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.hojaldresdivali.com.co\/en\/wp-json\/wp\/v2\/portfolio\/2572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hojaldresdivali.com.co\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.hojaldresdivali.com.co\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hojaldresdivali.com.co\/en\/wp-json\/wp\/v2\/comments?post=2572"}],"version-history":[{"count":0,"href":"https:\/\/www.hojaldresdivali.com.co\/en\/wp-json\/wp\/v2\/portfolio\/2572\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hojaldresdivali.com.co\/en\/wp-json\/wp\/v2\/media\/2573"}],"wp:attachment":[{"href":"https:\/\/www.hojaldresdivali.com.co\/en\/wp-json\/wp\/v2\/media?parent=2572"}],"wp:term":[{"taxonomy":"portfolio_cat","embeddable":true,"href":"https:\/\/www.hojaldresdivali.com.co\/en\/wp-json\/wp\/v2\/portfolio_cat?post=2572"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/www.hojaldresdivali.com.co\/en\/wp-json\/wp\/v2\/portfolio_skills?post=2572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}